{"id":16518,"date":"2023-02-17T09:40:03","date_gmt":"2023-02-17T09:40:03","guid":{"rendered":"https:\/\/eavest.fr\/?post_type=eavestpedia&#038;p=16518"},"modified":"2024-09-09T14:07:21","modified_gmt":"2024-09-09T14:07:21","slug":"comment-fonctionne-un-produit-phoenix-memoire","status":"publish","type":"eavestpedia","link":"https:\/\/eavest.fr\/en\/eavestpedia\/comment-fonctionne-un-produit-phoenix-memoire\/","title":{"rendered":"Comment fonctionne un produit de type &#8220;Phoenix M\u00e9moire&#8221; ?"},"content":{"rendered":"<p style=\"text-align: justify;\">Un produit Phoenix M\u00e9moire est un produit financier structur\u00e9 qui est automatiquement rembours\u00e9 par anticipation lorsque certaines conditions de march\u00e9 sont satisfaites. Il r\u00e9mun\u00e8re \u00e9galement l&#8217;investisseur sous la forme de coupons \u00e0 des dates de constatation sp\u00e9cifiques et permet de mettre en m\u00e9moire des coupons potentiellement perdus.<\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #0f45ff;\"><strong>M\u00e9canismes d\u2019un Phoenix M\u00e9moire :<\/strong><\/span><\/h3>\n<ul style=\"text-align: justify;\">\n<li>Si, \u00e0 l\u2019une des dates de constatation, le niveau du sous-jacent est sup\u00e9rieur au seuil de remboursement anticip\u00e9, alors le produit est automatiquement rembours\u00e9 (100% du nominal).<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Si \u00e0 l\u2019une des dates de constatation, le niveau du sous-jacent est sup\u00e9rieur au seuil de coupon mais inf\u00e9rieur au seuil de rappel, alors le produit verse un coupon de X % \u00e0 l\u2019investisseur mais n\u2019est pas rappel\u00e9<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li style=\"list-style-type: none;\">\n<ul style=\"text-align: justify;\">\n<li>Si \u00e0 l\u2019une des dates de constatation, le niveau du sous-jacent est sup\u00e9rieur au seuil de coupon mais inf\u00e9rieur au seuil de rappel, alors le produit verse \u00e0 la date de paiement, un montant \u00e9gal au coupon multipli\u00e9 par le nombre de p\u00e9riodes qui se sont \u00e9coul\u00e9es depuis le d\u00e9but du produit, moins la somme des coupons d\u00e9j\u00e0 pay\u00e9s. Le produit n\u2019est pas rappel\u00e9.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Si le niveau du sous-jacent n\u2019a jamais \u00e9t\u00e9 sup\u00e9rieur au seuil de remboursement anticip\u00e9, ni au seuil de coupon mais reste sup\u00e9rieur \u00e0 la barri\u00e8re de protection du capital \u00e9tablie, lors des dates de constatations pr\u00e9d\u00e9termin\u00e9es, le produit est rembours\u00e9 \u00e0 \u00e9ch\u00e9ance.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Les 3 sc\u00e9narios de performance ci-dessous permettent d\u2019illustrer le fonctionnement d\u2019un PHOENIX M\u00c9MOIRE.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-20081 aligncenter\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2023\/02\/phoenix-memoire-scenario-favorable-1-1.gif\" alt=\"\" width=\"960\" height=\"540\" \/><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16521 size-full aligncenter\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2023\/02\/EAVEST-Phoenix-Memoire-2-Scenario-Baissier-Protection-et-coupons-memoires.gif\" alt=\"Phoenix - Scenario Marche\u0301 Baissier pas de coupon\" width=\"960\" height=\"540\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-16519 size-full\" title=\"Gif phoenix m\u00e9moir sc\u00e9nario m\u00e9dian\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2023\/02\/EAVEST-Phoenix-3-Scenario-Marche\u0301-Baissier-pas-de-coupon.gif\" alt=\"Gif phoenix m\u00e9moir sc\u00e9nario m\u00e9dian\" width=\"960\" height=\"540\" \/><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #15ff16;\"><strong>Avantages d\u2019un Phoenix M\u00e9moire :<\/strong><\/span><\/h3>\n<ul style=\"text-align: justify;\">\n<li>Pendant la dur\u00e9e de vie du produit, l\u2019investisseur peut recevoir un coupon conditionnel de X % au titre de chaque p\u00e9riode, si, a\u0300 l\u2019une des dates de constatation, la performance du sous-jacent depuis la date de constatation initiale est sup\u00e9rieure ou \u00e9gale a\u0300 la barri\u00e8re de coupon. L\u2019investisseur pourra de plus r\u00e9cup\u00e9rer les coupons p\u00e9riodiques conditionnels de X % \u00e9ventuellement non vers\u00e9s pr\u00e9c\u00e9demment.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Si a\u0300 l\u2019une des dates de constatation, la performance de l&#8217;Indice est positive ou nulle depuis la date de constatation initiale, le m\u00e9canisme de remboursement anticipe\u0301 est automatiquement active\u0301. L\u2019investisseur re\u00e7oit alors l\u2019int\u00e9gralit\u00e9\u0301 du capital initial ainsi qu\u2019un coupon mensuel conditionnel de X % au titre de chaque p\u00e9riode.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>\u00c0 l\u2019\u00e9ch\u00e9ance, si le m\u00e9canisme de remboursement automatique anticipe\u0301 n\u2019a pas e\u0301te\u0301 active\u0301 pr\u00e9c\u00e9demment et si la performance de l&#8217;Indice est sup\u00e9rieure ou \u00e9gale au seuil de coupon depuis la date de constatation initiale, l\u2019investisseur re\u00e7oit alors l\u2019int\u00e9gralit\u00e9\u0301 du capital initial ainsi qu\u2019un coupon de X % au titre de la p\u00e9riode ainsi que les coupons conditionnels de X % \u00e9ventuellement non vers\u00e9s pr\u00e9c\u00e9demment.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>\u00c0 l\u2019\u00e9ch\u00e9ance, si le m\u00e9canisme de remboursement automatique anticipe\u0301 n\u2019a pas \u00e9t\u00e9 active\u0301 pr\u00e9c\u00e9demment et si la performance de l\u2019Indice est strictement inf\u00e9rieure au seuil de coupon mais sup\u00e9rieure ou \u00e9gale \u00e0 la barri\u00e8re de protection du capital depuis la date de constatation initiale, l\u2019investisseur re\u00e7oit alors l\u2019int\u00e9gralit\u00e9 du capital initial.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Effet m\u00e9moire : Si le niveau du sous-jacent n\u2019a pas d\u00e9pass\u00e9 le seuil de coupon \u00e0 l&#8217;une des dates de constatation, les coupons correspondants \u00e0 cette date ne sont pas imm\u00e9diatement vers\u00e9s \u00e0 l&#8217;investisseur. Au lieu de cela, ces coupons sont mis en attente et conserv\u00e9s en m\u00e9moire jusqu&#8217;\u00e0 la prochaine date de constatation o\u00f9 le niveau du sous-jacent d\u00e9passe le seuil de coupon. \u00c0 ce moment-l\u00e0, les coupons en m\u00e9moire sont d\u00e9bloqu\u00e9s et vers\u00e9s \u00e0 l&#8217;investisseur. Cela permet de r\u00e9cup\u00e9rer les coupons manquants lorsque les conditions du march\u00e9 sont plus favorables \u00e0 l&#8217;atteinte du seuil de coupon \u00e0 une date ult\u00e9rieure.<\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>Inconv\u00e9nients d\u2019un Phoenix M\u00e9moire :<\/strong><\/span><\/h3>\n<ul style=\"text-align: justify;\">\n<li>Le titre pr\u00e9sente un risque de perte partielle ou totale du capital en cours de vie (en cas de revente du titre de cr\u00e9ance a\u0300 l\u2019initiative de l\u2019investisseur alors que les conditions de remboursement automatique ne sont pas remplies, le prix d\u00e9pendant alors des param\u00e8tres de marche\u0301 le jour de la revente) et a\u0300 l\u2019\u00e9ch\u00e9ance (si, a\u0300 la Date d\u2019Observation Finale, le Niveau de l\u2019Indice est strictement inf\u00e9rieur a\u0300 X % de son Niveau Initial). La valorisation du titre \u00e0 l\u2019\u00e9ch\u00e9ance est tr\u00e8s sensible a\u0300 une faible variation du Niveau de l\u2019Indice autour des seuils de X % et X % de son Niveau Initial.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>L\u2019investisseur ne conna\u00eet pas a\u0300 l\u2019avance la dur\u00e9e exacte de son investissement qui peut varier du d\u00e9but des p\u00e9riodes d\u2019observation jusqu\u2019\u00e0 la maturit\u00e9 max du produit, si le m\u00e9canisme de remboursement automatique anticipe\u0301 n\u2019a pas \u00e9t\u00e9 active\u0301.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Le gain maximum de l\u2019investisseur est limite\u0301. L\u2019investisseur ne profite pas pleinement de la hausse du Niveau de l\u2019Indice (Effet de Plafonnement du Gain).<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>L\u2019investisseur est expose\u0301 a\u0300 un \u00e9ventuel d\u00e9faut (qui induit un risque de non-remboursement) ou a\u0300 une d\u00e9gradation de la qualit\u00e9\u0301 de cr\u00e9dit (qui induit un risque sur la valeur de marche\u0301 du titre de cr\u00e9ance) de l\u2019\u00e9metteur et a\u0300 un risque de d\u00e9faut, d\u2019ouverture d\u2019une proc\u00e9dure de r\u00e9solution et de faillite du Garant.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><span style=\"color: #ff0000;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18599\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2023\/02\/Capture.jpg\" alt=\"\" width=\"27\" height=\"23\" \/>\u00a0 Avertissement :\u00a0<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Les donn\u00e9es chiffr\u00e9es utilis\u00e9es dans ces illustrations n\u2019ont qu\u2019une valeur indicative et informative, l\u2019objectif \u00e9tant de d\u00e9crire le m\u00e9canisme du produit. Elles ne pr\u00e9jugent en rien des r\u00e9sultats futurs.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Ce titre risqu\u00e9 est une alternative \u00e0 un investissement dynamique risqu\u00e9 de type actions.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">L\u2019investisseur prend un risque de perte en capital partielle ou totale non mesurable a priori si le titre est revendu avant la date d\u2019\u00e9ch\u00e9ance ou la date de remboursement automatique anticip\u00e9 effective.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.produitsensouscription.com\/?code=def502008fff239ecf3b237021a24e8ae36411ccdd175e881fb53eae9d25be7d4fc9ac13997f215a53918c7cca33ca78dc6cf93df93ea399f34eb8aa898c1047cc63f53bfd1d488c674377553bc3d04a4e91445e499cfaee19ed03978016616a58fb838c0e6ecf5490e53624e227fb9292b877978ac2576d890bb50abd8dab79e3747aa34d07e7f44822d7196c73bffd2135437904605e6f28c7368374ac21596b99292a2b0b496bebb4bd5310cc9c804b37f26e35d1189dc03b407b59be16f37f2b7701391bc12285c43847a14a681de0e86b6abbd3314bb198189c8938c07b900d49e9da24e9a9cbf83814b9a0c2b721a1fd1ed907828c92bfb4ceaef57e9f4ed3021919d92a37173c7ac3a46ba428cf8319013270a441db25db93cb48134fd10f3e20e19bc955dde71386c632e488b2615f0d618388bb4e2f025a9ceb80051261af2e5c5e8413581e2a567c9e4d46f855114db87f1536d97e0d8e6c361cc1a09459af484c5c0be668ff6c4f4768211eb09ccfcbe11e658645812b343448b8170a92b03dc1732b10aa9a693d799cc781f0325b8d3282c7\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18775\" title=\"D\u00e9couvrez la premi\u00e8re marketplace de produits structur\u00e9s\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie.png\" alt=\"D\u00e9couvrez la premi\u00e8re marketplace de produits structur\u00e9s\" width=\"1000\" height=\"306\" srcset=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie.png 3963w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-300x92.png 300w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1024x313.png 1024w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-768x235.png 768w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1536x470.png 1536w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-2048x627.png 2048w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1900x582.png 1900w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1100x337.png 1100w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-800x245.png 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"sujet":[],"sous-categorie-titre":[],"class_list":["post-16518","eavestpedia","type-eavestpedia","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/eavestpedia\/16518\/"}],"collection":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/eavestpedia\/"}],"about":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/types\/eavestpedia\/"}],"wp:attachment":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/media\/?parent=16518"}],"wp:term":[{"taxonomy":"sujet","embeddable":true,"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sujet\/?post=16518"},{"taxonomy":"sous-categorie-titre","embeddable":true,"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sous-categorie-titre\/?post=16518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}