{"id":16576,"date":"2023-01-01T08:15:01","date_gmt":"2023-01-01T08:15:01","guid":{"rendered":"https:\/\/eavest.fr\/?post_type=eavestpedia&#038;p=16576"},"modified":"2024-07-18T14:56:17","modified_gmt":"2024-07-18T14:56:17","slug":"quest-ce-que-lindice-euronext-climate-objective-50-equal-weight-decrement","status":"publish","type":"eavestpedia","link":"https:\/\/eavest.fr\/en\/eavestpedia\/quest-ce-que-lindice-euronext-climate-objective-50-equal-weight-decrement\/","title":{"rendered":"Qu\u2019est-ce que l\u2019indice Euronext\u00ae Climate Objective 50 Equal Weight Decrement 5%?"},"content":{"rendered":"<h3>Sponsor : Natixis<\/h3>\n<h3>Code ISIN : NL0012328843<\/h3>\n<h3>Code Bloomberg : ECO50EW<\/h3>\n<p>&nbsp;<\/p>\n<p>L\u2019indice Euronext\u00ae Climate Objective 50 (indice Euronext\u00ae Climate Objective 50 Equal Weight Decrement 5 %), est un indice calcul\u00e9 et publi\u00e9 par Euronext, et est compos\u00e9 de 50 valeurs europ\u00e9ennes s\u00e9lectionn\u00e9es en fonction de l\u2019importance de leurs engagements en faveur du climat par rapport aux pratiques de leur secteur.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16646 size-full\" title=\"Qu\u2019est-ce que l\u2019indice Euronext\u00ae Climate Objective 50 Equal Weight Decrement 5%?\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2023\/03\/Euronext\u00ae-Climate-Objective-50-Equal-Weight-Decrement.jpg\" alt=\"Qu\u2019est-ce que l\u2019indice Euronext\u00ae Climate Objective 50 Equal Weight Decrement 5%?\" width=\"1103\" height=\"720\" srcset=\"https:\/\/eavest.fr\/wp-content\/uploads\/2023\/03\/Euronext\u00ae-Climate-Objective-50-Equal-Weight-Decrement.jpg 1103w, https:\/\/eavest.fr\/wp-content\/uploads\/2023\/03\/Euronext\u00ae-Climate-Objective-50-Equal-Weight-Decrement-300x196.jpg 300w, https:\/\/eavest.fr\/wp-content\/uploads\/2023\/03\/Euronext\u00ae-Climate-Objective-50-Equal-Weight-Decrement-1024x668.jpg 1024w, https:\/\/eavest.fr\/wp-content\/uploads\/2023\/03\/Euronext\u00ae-Climate-Objective-50-Equal-Weight-Decrement-768x501.jpg 768w, https:\/\/eavest.fr\/wp-content\/uploads\/2023\/03\/Euronext\u00ae-Climate-Objective-50-Equal-Weight-Decrement-1100x718.jpg 1100w, https:\/\/eavest.fr\/wp-content\/uploads\/2023\/03\/Euronext\u00ae-Climate-Objective-50-Equal-Weight-Decrement-800x522.jpg 800w\" sizes=\"auto, (max-width: 1103px) 100vw, 1103px\" \/><\/p>\n<p>Ces 50 valeurs sont \u00e9quipond\u00e9r\u00e9es, chacune des 50 valeurs repr\u00e9sente donc 1\/50e du poids de l\u2019Indice.<\/p>\n<p>Sa composition est revue \u00e0 une fr\u00e9quence annuelle.<\/p>\n<p>Euronext calcule l\u2019Indice de la fa\u00e7on suivante : en ajoutant tous les dividendes nets (vers\u00e9s par les actions composant l\u2019indice au fil de l\u2019eau tout le long de la vie du produit) puis en soustrayant 5,00 % par an sur une base quotidienne.<\/p>\n<p>Le montant moyen des dividendes pay\u00e9s par les valeurs composant l\u2019Indice sur les 8 derni\u00e8res ann\u00e9es s\u2019\u00e9l\u00e8ve \u00e0 3,80 %.<\/p>\n<p>Les montants des dividendes pass\u00e9s ne pr\u00e9jugent pas des montants des dividendes futurs.<\/p>\n<p>L\u2019indice Euronext\u00ae Climate Objective 50 est accessible entre autres sur le site d\u2019Euronext, ainsi que sur diff\u00e9rents sites d\u2019informations financi\u00e8res.<\/p>\n<p>Source :<a href=\"https:\/\/www.natixis.com\/natixis\/jcms\/j_6\/fr\/accueil\" target=\"_blank\" rel=\"noopener\">Natixis<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18599\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2023\/02\/Capture.jpg\" alt=\"\" width=\"27\" height=\"23\" \/>\u00a0\u00a0<span style=\"color: #ff0000;\">Avertissement :<\/span><\/strong><\/p>\n<p>Les donn\u00e9es relatives aux performances pass\u00e9es et\/ou simulations de performances pass\u00e9es ont trait ou se r\u00e9f\u00e8rent \u00e0 des p\u00e9riodes pass\u00e9es et ne sont pas un indicateur fiable des r\u00e9sultats futurs. Ceci est valable \u00e9galement pour les donn\u00e9es historiques de march\u00e9. Cette pr\u00e9sentation ne fait pas office de conseil en investissement.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.produitsensouscription.com\/?code=def502008fff239ecf3b237021a24e8ae36411ccdd175e881fb53eae9d25be7d4fc9ac13997f215a53918c7cca33ca78dc6cf93df93ea399f34eb8aa898c1047cc63f53bfd1d488c674377553bc3d04a4e91445e499cfaee19ed03978016616a58fb838c0e6ecf5490e53624e227fb9292b877978ac2576d890bb50abd8dab79e3747aa34d07e7f44822d7196c73bffd2135437904605e6f28c7368374ac21596b99292a2b0b496bebb4bd5310cc9c804b37f26e35d1189dc03b407b59be16f37f2b7701391bc12285c43847a14a681de0e86b6abbd3314bb198189c8938c07b900d49e9da24e9a9cbf83814b9a0c2b721a1fd1ed907828c92bfb4ceaef57e9f4ed3021919d92a37173c7ac3a46ba428cf8319013270a441db25db93cb48134fd10f3e20e19bc955dde71386c632e488b2615f0d618388bb4e2f025a9ceb80051261af2e5c5e8413581e2a567c9e4d46f855114db87f1536d97e0d8e6c361cc1a09459af484c5c0be668ff6c4f4768211eb09ccfcbe11e658645812b343448b8170a92b03dc1732b10aa9a693d799cc781f0325b8d3282c7\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18775\" title=\"Premi\u00e8re marketplace de produits structur\u00e9s\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie.png\" alt=\"Premi\u00e8re marketplace de produits structur\u00e9s\" width=\"1000\" height=\"306\" srcset=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie.png 3963w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-300x92.png 300w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1024x313.png 1024w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-768x235.png 768w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1536x470.png 1536w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-2048x627.png 2048w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1900x582.png 1900w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1100x337.png 1100w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-800x245.png 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"sujet":[],"sous-categorie-titre":[],"class_list":["post-16576","eavestpedia","type-eavestpedia","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/eavestpedia\/16576\/"}],"collection":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/eavestpedia\/"}],"about":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/types\/eavestpedia\/"}],"wp:attachment":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/media\/?parent=16576"}],"wp:term":[{"taxonomy":"sujet","embeddable":true,"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sujet\/?post=16576"},{"taxonomy":"sous-categorie-titre","embeddable":true,"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sous-categorie-titre\/?post=16576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}