{"id":17984,"date":"2024-01-11T09:48:41","date_gmt":"2024-01-11T09:48:41","guid":{"rendered":"https:\/\/eavest.fr\/?post_type=eavestpedia&#038;p=17984"},"modified":"2024-07-18T15:00:08","modified_gmt":"2024-07-18T15:00:08","slug":"quest-ce-que-lindice-euronext-climate-objective-50-euro-ew-decrement-5","status":"publish","type":"eavestpedia","link":"https:\/\/eavest.fr\/en\/eavestpedia\/quest-ce-que-lindice-euronext-climate-objective-50-euro-ew-decrement-5\/","title":{"rendered":"Qu\u2019est ce que l\u2019indice EURONEXT Climate Objective 50 EURO EW Decrement 5% ?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17985 size-full\" title=\"Qu\u2019est ce que l\u2019indice EURONEXT Climate Objective 50 EURO EW Decrement 5% ?\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-11-104257.png\" alt=\"Qu\u2019est ce que l\u2019indice EURONEXT Climate Objective 50 EURO EW Decrement 5% ?\" width=\"709\" height=\"268\" srcset=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-11-104257.png 709w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-11-104257-300x113.png 300w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">L\u2019indice <strong>Euronext\u00ae Climate Objective 50 Euro Equal Weight Decrement 5% (EWD5)<\/strong> a \u00e9t\u00e9 lanc\u00e9 par Euronext\u00ae le 5 septembre 2018, avec l\u2019appui de Carbone 4, expert et r\u00e9f\u00e9rent dans la strat\u00e9gie de r\u00e9duction de l\u2019empreinte carbone. L\u2019Indice est compos\u00e9 de 50 valeurs de la zone euro s\u00e9lectionn\u00e9es pour leur performance \u201cclimat\u201d. Ces 50 valeurs de l\u2019Indice sont \u00e9quipond\u00e9r\u00e9es. Une s\u00e9lection en ad\u00e9quation avec l\u2019approche climat de l\u2019\u00e9quipe GSH :<\/p>\n<ul style=\"text-align: justify;\">\n<li>R\u00e9duire l\u2019exposition aux risques que le climat fait peser sur les actifs,<\/li>\n<li>R\u00e9duire l\u2019impact des actifs sur le climat (et donc mesurer leur empreinte climat),<\/li>\n<li>Contribuer au financement de produits et solutions participant \u00e0 la transition \u00e9nerg\u00e9tique, Ainsi, les valeurs composant l\u2019Indice Euronext\u00ae Climate Objective 50 Euro EWD5 font part d\u2019une r\u00e9duction de l\u2019empreinte carbone importante compar\u00e9e \u00e0 leur environnement d\u2019investissement. L\u2019Indice est calcul\u00e9 de la fa\u00e7on suivante : en ajoutant tous les dividendes nets (vers\u00e9s par les actions composant l\u2019Indice au fil de l\u2019eau tout le long de la vie du produit) puis en soustrayant 5,00 % par an. Ce montant forfaitaire sert \u00e0 \u00e9liminer les incertitudes li\u00e9es au montant du dividende futur ainsi qu\u2019\u00e0 am\u00e9liorer le pricing des solutions d\u2019investissement<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Ticker Bloomberg : <span style=\"color: #0000ff;\"><strong>ECO5E Index<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18599\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2023\/02\/Capture.jpg\" alt=\"\" width=\"27\" height=\"23\" \/>\u00a0\u00a0<span style=\"color: #ff0000;\">Avertissement :<\/span><\/strong><\/p>\n<p>Les donn\u00e9es relatives aux performances pass\u00e9es et\/ou simulations de performances pass\u00e9es ont trait ou se r\u00e9f\u00e8rent \u00e0 des p\u00e9riodes pass\u00e9es et ne sont pas un indicateur fiable des r\u00e9sultats futurs. Ceci est valable \u00e9galement pour les donn\u00e9es historiques de march\u00e9. Cette pr\u00e9sentation ne fait pas office de conseil en investissement.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.produitsensouscription.com\/?code=def502008fff239ecf3b237021a24e8ae36411ccdd175e881fb53eae9d25be7d4fc9ac13997f215a53918c7cca33ca78dc6cf93df93ea399f34eb8aa898c1047cc63f53bfd1d488c674377553bc3d04a4e91445e499cfaee19ed03978016616a58fb838c0e6ecf5490e53624e227fb9292b877978ac2576d890bb50abd8dab79e3747aa34d07e7f44822d7196c73bffd2135437904605e6f28c7368374ac21596b99292a2b0b496bebb4bd5310cc9c804b37f26e35d1189dc03b407b59be16f37f2b7701391bc12285c43847a14a681de0e86b6abbd3314bb198189c8938c07b900d49e9da24e9a9cbf83814b9a0c2b721a1fd1ed907828c92bfb4ceaef57e9f4ed3021919d92a37173c7ac3a46ba428cf8319013270a441db25db93cb48134fd10f3e20e19bc955dde71386c632e488b2615f0d618388bb4e2f025a9ceb80051261af2e5c5e8413581e2a567c9e4d46f855114db87f1536d97e0d8e6c361cc1a09459af484c5c0be668ff6c4f4768211eb09ccfcbe11e658645812b343448b8170a92b03dc1732b10aa9a693d799cc781f0325b8d3282c7\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18775\" title=\"La premi\u00e8re marketplace de produits structur\u00e9s\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie.png\" alt=\"La premi\u00e8re marketplace de produits structur\u00e9s\" width=\"1000\" height=\"306\" srcset=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie.png 3963w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-300x92.png 300w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1024x313.png 1024w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-768x235.png 768w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1536x470.png 1536w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-2048x627.png 2048w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1900x582.png 1900w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1100x337.png 1100w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-800x245.png 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"sujet":[],"sous-categorie-titre":[],"class_list":["post-17984","eavestpedia","type-eavestpedia","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/eavestpedia\/17984\/"}],"collection":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/eavestpedia\/"}],"about":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/types\/eavestpedia\/"}],"wp:attachment":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/media\/?parent=17984"}],"wp:term":[{"taxonomy":"sujet","embeddable":true,"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sujet\/?post=17984"},{"taxonomy":"sous-categorie-titre","embeddable":true,"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sous-categorie-titre\/?post=17984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}