{"id":18010,"date":"2024-01-12T10:23:03","date_gmt":"2024-01-12T10:23:03","guid":{"rendered":"https:\/\/eavest.fr\/?post_type=eavestpedia&#038;p=18010"},"modified":"2024-07-18T15:01:23","modified_gmt":"2024-07-18T15:01:23","slug":"quest-ce-que-lindice-solactive-ethique-independance-et-gouvernance-responsable-france-30","status":"publish","type":"eavestpedia","link":"https:\/\/eavest.fr\/en\/eavestpedia\/quest-ce-que-lindice-solactive-ethique-independance-et-gouvernance-responsable-france-30\/","title":{"rendered":"Qu\u2019est ce que l\u2019indice SOLACTIVE Ethique, Independance et Gouvernance Responsable France 30 ?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18011 size-full\" title=\"Qu\u2019est ce que l\u2019indice SOLACTIVE Ethique, Independance et Gouvernance Responsable France 30 ?\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-12-110745.png\" alt=\"Qu\u2019est ce que l\u2019indice SOLACTIVE Ethique, Independance et Gouvernance Responsable France 30 ?\" width=\"694\" height=\"244\" srcset=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-12-110745.png 694w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-12-110745-300x105.png 300w\" sizes=\"auto, (max-width: 694px) 100vw, 694px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">L\u2019indice Solactive Ethique, Ind\u00e9pendance et Gouvernance Responsable France 30 a \u00e9t\u00e9 lanc\u00e9 en collaboration avec Solactive\u00ae et avec l\u2019agence ISS-ESG\u00ae, leader dans la recherche ESG et la notation extra fi nanci\u00e8re. L\u2019indice est compos\u00e9 de 30 entreprises fran\u00e7aises s\u00e9lectionn\u00e9es pour la qualit\u00e9 de leur gouvernance d\u2019entreprise. Ces 30 valeurs sont ensuite pond\u00e9r\u00e9es proportionnellement \u00e0 leur capitalisation boursi\u00e8re, plafonn\u00e9e \u00e0 7%. L\u2019indice est calcul\u00e9 de la fa\u00e7on suivante : en ajoutant tous les dividendes nets (vers\u00e9s par les actions composant l\u2019Indice au fi l de l\u2019eau tout le long de la vie du produit) puis en soustrayant 5,00 % par an. Le montant de 5,00 % est fi xe, et correspond au niveau m\u00e9dian des dividendes observ\u00e9s lors des ann\u00e9es pr\u00e9c\u00e9dentes. Ce montant forfaitaire sert \u00e0 \u00e9liminer les incertitudes li\u00e9es au montant du dividende futur ainsi qu\u2019\u00e0 am\u00e9liorer le pricing des solutions d\u2019investissemennt.<\/p>\n<p>&nbsp;<\/p>\n<h3>Ticker Bloomberg : <span style=\"color: #0000ff;\"><strong>SOLEIG Index<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18599\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2023\/02\/Capture.jpg\" alt=\"\" width=\"27\" height=\"23\" \/>\u00a0\u00a0<span style=\"color: #ff0000;\">Avertissement :<\/span><\/strong><\/p>\n<p>Les donn\u00e9es relatives aux performances pass\u00e9es et\/ou simulations de performances pass\u00e9es ont trait ou se r\u00e9f\u00e8rent \u00e0 des p\u00e9riodes pass\u00e9es et ne sont pas un indicateur fiable des r\u00e9sultats futurs. Ceci est valable \u00e9galement pour les donn\u00e9es historiques de march\u00e9. Cette pr\u00e9sentation ne fait pas office de conseil en investissement.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.produitsensouscription.com\/?code=def502008fff239ecf3b237021a24e8ae36411ccdd175e881fb53eae9d25be7d4fc9ac13997f215a53918c7cca33ca78dc6cf93df93ea399f34eb8aa898c1047cc63f53bfd1d488c674377553bc3d04a4e91445e499cfaee19ed03978016616a58fb838c0e6ecf5490e53624e227fb9292b877978ac2576d890bb50abd8dab79e3747aa34d07e7f44822d7196c73bffd2135437904605e6f28c7368374ac21596b99292a2b0b496bebb4bd5310cc9c804b37f26e35d1189dc03b407b59be16f37f2b7701391bc12285c43847a14a681de0e86b6abbd3314bb198189c8938c07b900d49e9da24e9a9cbf83814b9a0c2b721a1fd1ed907828c92bfb4ceaef57e9f4ed3021919d92a37173c7ac3a46ba428cf8319013270a441db25db93cb48134fd10f3e20e19bc955dde71386c632e488b2615f0d618388bb4e2f025a9ceb80051261af2e5c5e8413581e2a567c9e4d46f855114db87f1536d97e0d8e6c361cc1a09459af484c5c0be668ff6c4f4768211eb09ccfcbe11e658645812b343448b8170a92b03dc1732b10aa9a693d799cc781f0325b8d3282c7\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18775\" title=\"La premi\u00e8re marketplace de produits structur\u00e9s\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie.png\" alt=\"La premi\u00e8re marketplace de produits structur\u00e9s\" width=\"1000\" height=\"306\" srcset=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie.png 3963w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-300x92.png 300w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1024x313.png 1024w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-768x235.png 768w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1536x470.png 1536w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-2048x627.png 2048w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1900x582.png 1900w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1100x337.png 1100w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-800x245.png 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"sujet":[],"sous-categorie-titre":[],"class_list":["post-18010","eavestpedia","type-eavestpedia","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/eavestpedia\/18010\/"}],"collection":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/eavestpedia\/"}],"about":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/types\/eavestpedia\/"}],"wp:attachment":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/media\/?parent=18010"}],"wp:term":[{"taxonomy":"sujet","embeddable":true,"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sujet\/?post=18010"},{"taxonomy":"sous-categorie-titre","embeddable":true,"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sous-categorie-titre\/?post=18010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}