{"id":18383,"date":"2024-01-17T16:24:37","date_gmt":"2024-01-17T16:24:37","guid":{"rendered":"https:\/\/eavest.fr\/?post_type=eavestpedia&#038;p=18383"},"modified":"2024-07-18T15:05:20","modified_gmt":"2024-07-18T15:05:20","slug":"quest-ce-que-lindice-sp-eurozone-50-net-zero-2050-paris-aligned-select-50-point-decrement","status":"publish","type":"eavestpedia","link":"https:\/\/eavest.fr\/en\/eavestpedia\/quest-ce-que-lindice-sp-eurozone-50-net-zero-2050-paris-aligned-select-50-point-decrement\/","title":{"rendered":"Qu\u2019est ce que l\u2019indice S&#038;P Eurozone 50 Net Zero 2050 Paris-Aligned  Select 50 Point Decrement ?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18384 size-full\" title=\"Qu\u2019est ce que l\u2019indice S&amp;P Eurozone 50 Net Zero 2050 Paris-Aligned Select 50 Point Decrement ?\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-17-172209.png\" alt=\"Qu\u2019est ce que l\u2019indice S&amp;P Eurozone 50 Net Zero 2050 Paris-Aligned Select 50 Point Decrement ?\" width=\"868\" height=\"231\" srcset=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-17-172209.png 868w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-17-172209-300x80.png 300w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-17-172209-768x204.png 768w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/01\/Capture-decran-2024-01-17-172209-800x213.png 800w\" sizes=\"auto, (max-width: 868px) 100vw, 868px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">En 2015, l\u2019Union Europ\u00e9enne a sign\u00e9 l\u2019Accord de Paris sur le climat, qui fixe comme objectif de renforcer la riposte \u00e0 la menace des changements climatiques. Puis en 2019, la Commission a adopt\u00e9 \u00ab\u00a0 Le pacte vert pour l\u2019Europe\u00a0\u00bb, qui vise \u00e0 transformer l\u2019UE en une soci\u00e9t\u00e9 juste et prosp\u00e8re, dot\u00e9e d\u2019une \u00e9conomie moderne, dans laquelle les \u00e9missions nettes de gaz \u00e0 effet de serre seront devenues nulles en 2050, et dans laquelle l\u2019environnement et la sant\u00e9 des citoyens seront prot\u00e9g\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Puisque la majeure partie des investissements durables devra venir des entreprises et des m\u00e9nages au cours de la prochaine d\u00e9cennie, il est essentiel de donner aux investisseurs des signaux clairs de long terme pour les guider vers des investissements durables. Le r\u00e8glement sur les indices de r\u00e9f\u00e9rence vot\u00e9 par la Commission Europ\u00e9enne instaure un cadre commun visant \u00e0 garantir l\u2019exactitude et l\u2019int\u00e9grit\u00e9 des indices utilis\u00e9s comme indices de r\u00e9f\u00e9rence dans le cadre d\u2019instruments financiers dans l\u2019Union Europ\u00e9enne.<\/p>\n<p style=\"text-align: justify;\">Ce r\u00e8glement introduit donc une nouvelle cat\u00e9gorie d\u2019indices de r\u00e9f\u00e9rence, \u00e0 savoir les indices de r\u00e9f\u00e9rence de l\u2019Union en mati\u00e8re climatique : les indices de r\u00e9f\u00e9rence Transition Climatique (\u00ab CTB \u00bb) de l\u2019Union et les indices de r\u00e9f\u00e9rence Accord de Paris (\u00ab PAB \u00bb) de l\u2019Union. Ce texte \u00e9tablit surtout les normes minimales que les indices de r\u00e9f\u00e9rence de l\u2019Union devraient respecter pour pouvoir se pr\u00e9senter sous ces d\u00e9nominations.<\/p>\n<p>&nbsp;<\/p>\n<h3>Ticker Bloomberg : <span style=\"color: #0000ff;\"><strong>SPEZPDET Index<\/strong><\/span><\/h3>\n<hr \/>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18599\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2023\/02\/Capture.jpg\" alt=\"\" width=\"27\" height=\"23\" \/>\u00a0\u00a0<span style=\"color: #ff0000;\">Avertissement :<\/span><\/strong><\/p>\n<p>Les donn\u00e9es relatives aux performances pass\u00e9es et\/ou simulations de performances pass\u00e9es ont trait ou se r\u00e9f\u00e8rent \u00e0 des p\u00e9riodes pass\u00e9es et ne sont pas un indicateur fiable des r\u00e9sultats futurs. Ceci est valable \u00e9galement pour les donn\u00e9es historiques de march\u00e9. Cette pr\u00e9sentation ne fait pas office de conseil en investissement.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.produitsensouscription.com\/?code=def502008fff239ecf3b237021a24e8ae36411ccdd175e881fb53eae9d25be7d4fc9ac13997f215a53918c7cca33ca78dc6cf93df93ea399f34eb8aa898c1047cc63f53bfd1d488c674377553bc3d04a4e91445e499cfaee19ed03978016616a58fb838c0e6ecf5490e53624e227fb9292b877978ac2576d890bb50abd8dab79e3747aa34d07e7f44822d7196c73bffd2135437904605e6f28c7368374ac21596b99292a2b0b496bebb4bd5310cc9c804b37f26e35d1189dc03b407b59be16f37f2b7701391bc12285c43847a14a681de0e86b6abbd3314bb198189c8938c07b900d49e9da24e9a9cbf83814b9a0c2b721a1fd1ed907828c92bfb4ceaef57e9f4ed3021919d92a37173c7ac3a46ba428cf8319013270a441db25db93cb48134fd10f3e20e19bc955dde71386c632e488b2615f0d618388bb4e2f025a9ceb80051261af2e5c5e8413581e2a567c9e4d46f855114db87f1536d97e0d8e6c361cc1a09459af484c5c0be668ff6c4f4768211eb09ccfcbe11e658645812b343448b8170a92b03dc1732b10aa9a693d799cc781f0325b8d3282c7\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18775\" title=\"La premi\u00e8re marketplace de produits structur\u00e9s\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie.png\" alt=\"La premi\u00e8re marketplace de produits structur\u00e9s\" width=\"1000\" height=\"306\" srcset=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie.png 3963w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-300x92.png 300w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1024x313.png 1024w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-768x235.png 768w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1536x470.png 1536w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-2048x627.png 2048w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1900x582.png 1900w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1100x337.png 1100w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-800x245.png 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"sujet":[],"sous-categorie-titre":[],"class_list":["post-18383","eavestpedia","type-eavestpedia","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/eavestpedia\/18383\/"}],"collection":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/eavestpedia\/"}],"about":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/types\/eavestpedia\/"}],"wp:attachment":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/media\/?parent=18383"}],"wp:term":[{"taxonomy":"sujet","embeddable":true,"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sujet\/?post=18383"},{"taxonomy":"sous-categorie-titre","embeddable":true,"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sous-categorie-titre\/?post=18383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}