{"id":18987,"date":"2024-04-03T12:41:25","date_gmt":"2024-04-03T12:41:25","guid":{"rendered":"https:\/\/eavest.fr\/?post_type=eavestpedia&#038;p=18987"},"modified":"2024-07-20T14:43:52","modified_gmt":"2024-07-20T14:43:52","slug":"quest-ce-quun-social-bond","status":"publish","type":"eavestpedia","link":"https:\/\/eavest.fr\/en\/eavestpedia\/quest-ce-quun-social-bond\/","title":{"rendered":"Qu\u2019est ce qu\u2019un Social Bond ?"},"content":{"rendered":"<p>Un \u00ab social bond \u00bb (obligation sociale) est un instrument financier \u00e9mis par un gouvernement, une entreprise ou une institution financi\u00e8re pour financer des projets \u00e0 impact social positif. Ce type d&#8217;obligation a gagn\u00e9 en popularit\u00e9 ces derni\u00e8res ann\u00e9es en raison de l&#8217;importance croissante accord\u00e9e aux questions sociales et environnementales par les investisseurs et la soci\u00e9t\u00e9 en g\u00e9n\u00e9ral.<\/p>\n<p>Les fonds lev\u00e9s gr\u00e2ce \u00e0 ces obligations peuvent \u00eatre utilis\u00e9s pour des projets tels que la construction d\u2019infrastructures sociales (comme des \u00e9coles ou des h\u00f4pitaux), des programmes de lutte contre la pauvret\u00e9, des initiatives de d\u00e9veloppement durable, ou encore des projets visant \u00e0 promouvoir l\u2019emploi et l\u2019inclusion sociale. Par exemple, un gouvernement peut \u00e9mettre des social bonds pour financer la construction de logements abordables, ce qui contribue \u00e0 r\u00e9duire les in\u00e9galit\u00e9s sociales et \u00e0 am\u00e9liorer la qualit\u00e9 de vie des populations d\u00e9favoris\u00e9es.<\/p>\n<p>De plus, les entreprises peuvent \u00e9galement \u00e9mettre des social bonds pour financer des programmes de formation et de d\u00e9veloppement des comp\u00e9tences pour les travailleurs, des initiatives de diversit\u00e9 et d&#8217;inclusion, ou des projets visant \u00e0 r\u00e9duire leur empreinte carbone. Ces actions permettent non seulement d\u2019am\u00e9liorer la r\u00e9putation des entreprises \u00e9mettrices, mais aussi de r\u00e9pondre aux attentes des investisseurs socialement responsables qui cherchent \u00e0 investir dans des projets ayant un impact positif sur la soci\u00e9t\u00e9.<\/p>\n<p>Les social bonds se rapprochent donc tr\u00e8s souvent des crit\u00e8res des Objectifs de D\u00e9veloppement Durable (ODD) d\u00e9finis par les Nations Unies, qui visent \u00e0 \u00e9radiquer la pauvret\u00e9, prot\u00e9ger la plan\u00e8te et garantir la prosp\u00e9rit\u00e9 pour tous d\u2019ici 2030. En alignant leurs projets financ\u00e9s par des social bonds sur les ODD, les \u00e9metteurs peuvent attirer un plus large \u00e9ventail d&#8217;investisseurs et contribuer \u00e0 la r\u00e9alisation de ces objectifs globaux.<\/p>\n<p>De ce fait, les social bonds soutiennent fortement une transition vers une \u00e9conomie avec une meilleure gouvernance sociale. En effet, ils encouragent les \u00e9metteurs \u00e0 adopter des pratiques commerciales plus responsables et \u00e0 investir dans des projets qui b\u00e9n\u00e9ficient \u00e0 la soci\u00e9t\u00e9 dans son ensemble. En fin de compte, les social bonds peuvent jouer un r\u00f4le crucial dans la promotion d&#8217;une croissance \u00e9conomique inclusive et durable, tout en r\u00e9pondant aux d\u00e9fis sociaux et environnementaux actuels.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18599\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2023\/02\/Capture.jpg\" alt=\"\" width=\"27\" height=\"23\" \/>\u00a0 <span style=\"color: #ff0000;\">Avertissement :<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Les donn\u00e9es relatives aux performances pass\u00e9es et\/ou simulations de performances pass\u00e9es ont trait ou se r\u00e9f\u00e8rent \u00e0 des p\u00e9riodes pass\u00e9es et ne sont pas un indicateur fiable des r\u00e9sultats futurs. Ceci est valable \u00e9galement pour les donn\u00e9es historiques de march\u00e9. Cette pr\u00e9sentation ne fait pas office de conseil en investissement.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.produitsensouscription.com\/?code=def502008fff239ecf3b237021a24e8ae36411ccdd175e881fb53eae9d25be7d4fc9ac13997f215a53918c7cca33ca78dc6cf93df93ea399f34eb8aa898c1047cc63f53bfd1d488c674377553bc3d04a4e91445e499cfaee19ed03978016616a58fb838c0e6ecf5490e53624e227fb9292b877978ac2576d890bb50abd8dab79e3747aa34d07e7f44822d7196c73bffd2135437904605e6f28c7368374ac21596b99292a2b0b496bebb4bd5310cc9c804b37f26e35d1189dc03b407b59be16f37f2b7701391bc12285c43847a14a681de0e86b6abbd3314bb198189c8938c07b900d49e9da24e9a9cbf83814b9a0c2b721a1fd1ed907828c92bfb4ceaef57e9f4ed3021919d92a37173c7ac3a46ba428cf8319013270a441db25db93cb48134fd10f3e20e19bc955dde71386c632e488b2615f0d618388bb4e2f025a9ceb80051261af2e5c5e8413581e2a567c9e4d46f855114db87f1536d97e0d8e6c361cc1a09459af484c5c0be668ff6c4f4768211eb09ccfcbe11e658645812b343448b8170a92b03dc1732b10aa9a693d799cc781f0325b8d3282c7\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-18775\" title=\"D\u00e9couvrez la premi\u00e8re marketplace de produits structur\u00e9s\" src=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie.png\" alt=\"D\u00e9couvrez la premi\u00e8re marketplace de produits structur\u00e9s\" width=\"1000\" height=\"306\" srcset=\"https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie.png 3963w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-300x92.png 300w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1024x313.png 1024w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-768x235.png 768w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1536x470.png 1536w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-2048x627.png 2048w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1900x582.png 1900w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-1100x337.png 1100w, https:\/\/eavest.fr\/wp-content\/uploads\/2024\/03\/ELEMENTS_Plan-de-travail-1-copie-800x245.png 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"sujet":[],"sous-categorie-titre":[],"class_list":["post-18987","eavestpedia","type-eavestpedia","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/eavestpedia\/18987\/"}],"collection":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/eavestpedia\/"}],"about":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/types\/eavestpedia\/"}],"wp:attachment":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/media\/?parent=18987"}],"wp:term":[{"taxonomy":"sujet","embeddable":true,"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sujet\/?post=18987"},{"taxonomy":"sous-categorie-titre","embeddable":true,"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sous-categorie-titre\/?post=18987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}