{"id":71,"count":0,"description":"Bienvenue dans notre cat\u00e9gorie d\u00e9di\u00e9e aux produits structur\u00e9s sous-jacents ESG. Ici, vous d\u00e9couvrirez une s\u00e9lection diversifi\u00e9e de solutions d'investissement qui int\u00e8grent des crit\u00e8res Environnementaux, Sociaux et de Gouvernance (ESG) au c\u0153ur de leur strat\u00e9gie. Nos produits structur\u00e9s ESG sont con\u00e7us pour r\u00e9pondre aux attentes des investisseurs soucieux de concilier performance financi\u00e8re et responsabilit\u00e9 soci\u00e9tale.","link":"https:\/\/eavest.fr\/sujet\/les-sous-jacents-esg\/","name":"Les sous-jacents ESG","slug":"les-sous-jacents-esg","taxonomy":"sujet","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sujet\/71\/"}],"collection":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/sujet\/"}],"about":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/taxonomies\/sujet\/"}],"wp:post_type":[{"href":"https:\/\/eavest.fr\/en\/wp-json\/wp\/v2\/eavestpedia\/?sujet=71"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}